{"id":4765,"date":"2020-05-25T11:01:00","date_gmt":"2020-05-25T11:01:00","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?p=4765"},"modified":"2025-05-06T17:45:09","modified_gmt":"2025-05-06T17:45:09","slug":"pruebas-pevau","status":"publish","type":"post","link":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/","title":{"rendered":"PRUEBAS PEvAU"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Estructura de la PEvAU adaptada a la situaci\u00f3n acad\u00e9mica producida por el Covid-19. Consulta aqu\u00ed contenidos y estructuras del ex\u00e1men. <a href=\"https:\/\/www.juntadeandalucia.es\/economiaconocimientoempresasyuniversidad\/sguit\/?q=grados&amp;d=g_b_modelos_examen_covid19.php\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #00ccff;\">[ INFORMACI\u00d3N ]<\/span><\/a><\/p>\n<p>&nbsp;<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Estructura de la PEvAU adaptada a la situaci\u00f3n acad\u00e9mica producida por el Covid-19. Consulta aqu\u00ed contenidos y estructuras del ex\u00e1men. [ INFORMACI\u00d3N ] &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":4252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRUEBAS PEvAU - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRUEBAS PEvAU - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"Estructura de la PEvAU adaptada a la situaci\u00f3n acad\u00e9mica producida por el Covid-19. Consulta aqu\u00ed contenidos y estructuras del ex\u00e1men. [ INFORMACI\u00d3N ] &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T11:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:45:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/examen01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"headline\":\"PRUEBAS PEvAU\",\"datePublished\":\"2020-05-25T11:01:00+00:00\",\"dateModified\":\"2025-05-06T17:45:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/\"},\"wordCount\":99,\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/examen01.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/\",\"name\":\"PRUEBAS PEvAU - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/examen01.jpg\",\"datePublished\":\"2020-05-25T11:01:00+00:00\",\"dateModified\":\"2025-05-06T17:45:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/examen01.jpg\",\"contentUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/examen01.jpg\",\"width\":620,\"height\":349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2020\\\/05\\\/25\\\/pruebas-pevau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRUEBAS PEvAU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/iesfernandoaguilar.es\"],\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/author\\\/nimda_faq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRUEBAS PEvAU - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/","og_locale":"es_ES","og_type":"article","og_title":"PRUEBAS PEvAU - IES Fernando Aguilar Quignon","og_description":"Estructura de la PEvAU adaptada a la situaci\u00f3n acad\u00e9mica producida por el Covid-19. Consulta aqu\u00ed contenidos y estructuras del ex\u00e1men. [ INFORMACI\u00d3N ] &nbsp;","og_url":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/","og_site_name":"IES Fernando Aguilar Quignon","article_published_time":"2020-05-25T11:01:00+00:00","article_modified_time":"2025-05-06T17:45:09+00:00","og_image":[{"width":620,"height":349,"url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/examen01.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#article","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/"},"author":{"name":"admin","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"headline":"PRUEBAS PEvAU","datePublished":"2020-05-25T11:01:00+00:00","dateModified":"2025-05-06T17:45:09+00:00","mainEntityOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/"},"wordCount":99,"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/examen01.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/","url":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/","name":"PRUEBAS PEvAU - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#primaryimage"},"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/examen01.jpg","datePublished":"2020-05-25T11:01:00+00:00","dateModified":"2025-05-06T17:45:09+00:00","author":{"@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"breadcrumb":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#primaryimage","url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/examen01.jpg","contentUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/examen01.jpg","width":620,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2020\/05\/25\/pruebas-pevau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iesfernandoaguilar.es\/"},{"@type":"ListItem","position":2,"name":"PRUEBAS PEvAU"}]},{"@type":"WebSite","@id":"https:\/\/iesfernandoaguilar.es\/#website","url":"https:\/\/iesfernandoaguilar.es\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iesfernandoaguilar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/iesfernandoaguilar.es"],"url":"https:\/\/iesfernandoaguilar.es\/index.php\/author\/nimda_faq\/"}]}},"_links":{"self":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/comments?post=4765"}],"version-history":[{"count":3,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4765\/revisions"}],"predecessor-version":[{"id":4768,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4765\/revisions\/4768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media\/4252"}],"wp:attachment":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media?parent=4765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/categories?post=4765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/tags?post=4765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}