{"id":4644,"date":"2019-03-05T10:13:00","date_gmt":"2019-03-05T10:13:00","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?p=4644"},"modified":"2025-05-06T17:45:10","modified_gmt":"2025-05-06T17:45:10","slug":"jornada-de-puertas-abiertas","status":"publish","type":"post","link":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/","title":{"rendered":"JORNADA DE PUERTAS ABIERTAS"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El pr\u00f3ximo Martes 12 Marzo a las 18:00 h. tendremos la jornada de puertas abiertas para poder dar a conocer nuestro centro a los padres y madres del alumnado de 6\u00ba de Primaria de los centros adscritos (CEIP Tiernos Galv\u00e1n y CEIP Ferm\u00edn Salvochea) y para todas las familias que quieran acercarse a conocer de primera mano nuestra oferta educativa.<\/p>\n<p>Por la ma\u00f1ana est\u00e1 previsto que el alumnado de 6\u00ba de Primaria de estos centros asistan al centro para tomar contacto con el que ser\u00e1 su instituto en unos meses.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo Martes 12 Marzo a las 18:00 h. tendremos la jornada de puertas abiertas para poder dar a conocer nuestro centro a los padres y madres del alumnado de 6\u00ba de Primaria de los centros adscritos (CEIP Tiernos Galv\u00e1n y CEIP Ferm\u00edn Salvochea) y para todas las familias que quieran acercarse a conocer de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JORNADA DE PUERTAS ABIERTAS - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JORNADA DE PUERTAS ABIERTAS - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo Martes 12 Marzo a las 18:00 h. tendremos la jornada de puertas abiertas para poder dar a conocer nuestro centro a los padres y madres del alumnado de 6\u00ba de Primaria de los centros adscritos (CEIP Tiernos Galv\u00e1n y CEIP Ferm\u00edn Salvochea) y para todas las familias que quieran acercarse a conocer de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-05T10:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:45:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/fachada-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"headline\":\"JORNADA DE PUERTAS ABIERTAS\",\"datePublished\":\"2019-03-05T10:13:00+00:00\",\"dateModified\":\"2025-05-06T17:45:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/\"},\"wordCount\":165,\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fachada-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/\",\"name\":\"JORNADA DE PUERTAS ABIERTAS - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fachada-1.jpg\",\"datePublished\":\"2019-03-05T10:13:00+00:00\",\"dateModified\":\"2025-05-06T17:45:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fachada-1.jpg\",\"contentUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fachada-1.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2019\\\/03\\\/05\\\/jornada-de-puertas-abiertas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JORNADA DE PUERTAS ABIERTAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/iesfernandoaguilar.es\"],\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/author\\\/nimda_faq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JORNADA DE PUERTAS ABIERTAS - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/","og_locale":"es_ES","og_type":"article","og_title":"JORNADA DE PUERTAS ABIERTAS - IES Fernando Aguilar Quignon","og_description":"El pr\u00f3ximo Martes 12 Marzo a las 18:00 h. tendremos la jornada de puertas abiertas para poder dar a conocer nuestro centro a los padres y madres del alumnado de 6\u00ba de Primaria de los centros adscritos (CEIP Tiernos Galv\u00e1n y CEIP Ferm\u00edn Salvochea) y para todas las familias que quieran acercarse a conocer de [&hellip;]","og_url":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/","og_site_name":"IES Fernando Aguilar Quignon","article_published_time":"2019-03-05T10:13:00+00:00","article_modified_time":"2025-05-06T17:45:10+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/fachada-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#article","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/"},"author":{"name":"admin","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"headline":"JORNADA DE PUERTAS ABIERTAS","datePublished":"2019-03-05T10:13:00+00:00","dateModified":"2025-05-06T17:45:10+00:00","mainEntityOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/"},"wordCount":165,"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/fachada-1.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/","url":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/","name":"JORNADA DE PUERTAS ABIERTAS - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#primaryimage"},"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/fachada-1.jpg","datePublished":"2019-03-05T10:13:00+00:00","dateModified":"2025-05-06T17:45:10+00:00","author":{"@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"breadcrumb":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#primaryimage","url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/fachada-1.jpg","contentUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/fachada-1.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2019\/03\/05\/jornada-de-puertas-abiertas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iesfernandoaguilar.es\/"},{"@type":"ListItem","position":2,"name":"JORNADA DE PUERTAS ABIERTAS"}]},{"@type":"WebSite","@id":"https:\/\/iesfernandoaguilar.es\/#website","url":"https:\/\/iesfernandoaguilar.es\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iesfernandoaguilar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/iesfernandoaguilar.es"],"url":"https:\/\/iesfernandoaguilar.es\/index.php\/author\/nimda_faq\/"}]}},"_links":{"self":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/comments?post=4644"}],"version-history":[{"count":3,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4644\/revisions"}],"predecessor-version":[{"id":4647,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4644\/revisions\/4647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media\/4256"}],"wp:attachment":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media?parent=4644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/categories?post=4644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/tags?post=4644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}