{"id":4601,"date":"2018-07-25T10:00:00","date_gmt":"2018-07-25T10:00:00","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?p=4601"},"modified":"2025-05-06T17:45:11","modified_gmt":"2025-05-06T17:45:11","slug":"elecciones-al-consejo-escolar-2","status":"publish","type":"post","link":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/","title":{"rendered":"ELECCIONES AL CONSEJO ESCOLAR"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>El Consejo escolar es un \u00f3rgano colegiado de Participaci\u00f3n de la comunidad educativa en el gobierno del centro. La Constituci\u00f3n Espa\u00f1ola, en su art\u00edculo 27, establece que \u00abLos profesores, los padres y, en su caso, los alumnos intervendr\u00e1n en el control y gesti\u00f3n de todos los centros sostenidos por la Administraci\u00f3n con fondos p\u00fablicos\u00bb; este principio de participaci\u00f3n constituye el principal instrumento para que toda la comunidad educativa pueda implicarse directamente en la toma de decisiones del mismo.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"auto-style40\"><span>Renovamos nuestro Consejo Escolar. Es una oportunidad para ejercer nuestro voto y respaldar a nuestros representantes en el mayor \u00f3rgano\u00a0\u00a0de gobierno del centro.<o:p><\/o:p><\/span><\/p>\n<p class=\"auto-style4\">\n<p class=\"auto-style4\">Una vez celebradas las elecciones, este es el resultado del escrutinio:<\/p>\n<p class=\"auto-style4\">\n<table cellpadding=\"3\" cellspacing=\"0\" class=\"auto-style11\">\n<tbody>\n<tr>\n<td class=\"auto-style16\" colspan=\"2\"><strong>SECTOR PROFESORADO<\/strong><\/td>\n<td class=\"auto-style25\" colspan=\"2\"><strong>SECTOR ALUMNADO<\/strong><\/td>\n<td class=\"auto-style25\" colspan=\"2\"><strong>SECTOR PADRES\/MADRES<\/strong><\/td>\n<td class=\"auto-style15\" colspan=\"2\"><strong>SECTOR P.A.S.<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style17\">Candidato\/a<\/td>\n<td class=\"auto-style24\">Votos<\/td>\n<td class=\"auto-style23\">Candidato\/a<\/td>\n<td class=\"auto-style24\">Votos<\/td>\n<td class=\"auto-style23\">Candidato\/a<\/td>\n<td class=\"auto-style24\">Votos<\/td>\n<td class=\"auto-style23\">Candidato\/a<\/td>\n<td class=\"auto-style21\">Votos<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Barro Zarco, Inmaculada<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">48<\/td>\n<td class=\"auto-style37\">\n<p class=\"auto-style46\">Barea Rivas, Miguel Angel<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">5<\/td>\n<td class=\"auto-style29\">\n<p class=\"auto-style39\">Duran Rosety, Cristina<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">16<\/td>\n<td class=\"auto-style52\">Garc\u00eda Gonz\u00e1lez, Victoria<\/td>\n<td class=\"auto-style54\">8<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Fern\u00e1ndez Fern\u00e1ndez, Pedro<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">50<\/td>\n<td class=\"auto-style37\">\n<p class=\"auto-style46\">Beardo Fuentes, Mar\u00eda<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">7<\/td>\n<td class=\"auto-style29\">\n<p class=\"auto-style39\">M\u00e1rquez Garc\u00eda, Juana<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">8<\/td>\n<td class=\"auto-style41\">\u00a0<\/td>\n<td class=\"auto-style22\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Fern\u00e1ndez Serrano, Antonio<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">40<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style46\">Bruz\u00f3n Jim\u00e9nez, Luc\u00eda<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">9<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style50\">Morales Pi\u00f1ero, Gema<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">18<\/td>\n<td class=\"auto-style41\">\u00a0<\/td>\n<td class=\"auto-style20\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Hermida Prieto, Ana<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">45<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style46\">Calo del Pino, Eva<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">10<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style50\">Palma Gaeta, Roc\u00edo<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">24<\/td>\n<td class=\"auto-style12\"><\/td>\n<td class=\"auto-style20\"><\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Herrero Medina, Vicente<\/p>\n<\/td>\n<td class=\"auto-style45\">41<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style46\">Campoy Guerra, Alejandra<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">29<\/td>\n<td class=\"auto-style12\">\n<p class=\"auto-style46\">Romero Ordu\u00f1a, M\u00aa del Carmen<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">15<\/td>\n<td class=\"auto-style41\"><\/td>\n<td class=\"auto-style20\"><\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Rey Pelayo, Manuel<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">51<\/td>\n<td class=\"auto-style12\">\n<p class=\"auto-style46\">Carpintero Postiguillo, Caridad<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">6<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style50\">S\u00e1nchez Noguera, Sebasti\u00e1n<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">21<\/td>\n<td class=\"auto-style41\">\u00a0<\/td>\n<td class=\"auto-style20\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">\n<p class=\"auto-style46\">Rosales Prieto, Gloria Mar\u00eda<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style45\">44<\/td>\n<td class=\"auto-style12\">\n<p class=\"auto-style46\">Guerra Alvarez, Paula<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style13\">7<\/td>\n<td class=\"auto-style52\">Vegas Mart\u00edn, Adoraci\u00f3n<\/td>\n<td class=\"auto-style45\">20<\/td>\n<td class=\"auto-style41\">\u00a0<\/td>\n<td class=\"auto-style20\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style49\">Vilallobos Beatty, Mercedes<\/td>\n<td class=\"auto-style45\">49<\/td>\n<td class=\"auto-style51\">\n<p class=\"auto-style50\">Jim\u00e9nez Guiti\u00e9rrez, Luc\u00eda<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style54\">9<\/td>\n<td class=\"auto-style12\"><\/td>\n<td class=\"auto-style26\"><\/td>\n<td class=\"auto-style12\"><\/td>\n<td class=\"auto-style20\"><\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style48\">\u00a0<\/td>\n<td class=\"auto-style13\">\u00a0<\/td>\n<td class=\"auto-style12\">\n<p class=\"auto-style46\">L\u00f3pez-Qui\u00f1ones G\u00f3mez, Marina<o:p><\/o:p><\/p>\n<\/td>\n<td class=\"auto-style53\">3<\/td>\n<td class=\"auto-style12\"><\/td>\n<td class=\"auto-style26\"><\/td>\n<td class=\"auto-style12\"><\/td>\n<td class=\"auto-style20\"><\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style48\">\u00a0<\/td>\n<td class=\"auto-style13\">\u00a0<\/td>\n<td class=\"auto-style52\">Vargas Miranda, Alejandro<\/td>\n<td class=\"auto-style45\">8<\/td>\n<td class=\"auto-style41\">\u00a0<\/td>\n<td class=\"auto-style47\">\u00a0<\/td>\n<td class=\"auto-style41\">\u00a0<\/td>\n<td class=\"auto-style20\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"auto-style22\"><br class=\"auto-style34\" \/><span class=\"auto-style34\">Entran a formar parte del Consejo Escolar<span>\u00a0<\/span><span class=\"auto-style35\"><strong>8<\/strong><\/span><span>\u00a0<\/span>profesores\/as<\/span><\/td>\n<td class=\"auto-style32\">\u00a0<\/td>\n<td class=\"auto-style36\"><br class=\"auto-style34\" \/><span class=\"auto-style34\">Entran a formar parte del Consejo Escolar<span>\u00a0<\/span><span class=\"auto-style35\"><strong>5<\/strong><\/span><span>\u00a0<\/span>alumnos\/as<\/span><\/td>\n<td class=\"auto-style32\">\u00a0<\/td>\n<td class=\"auto-style36\"><br class=\"auto-style34\" \/><span class=\"auto-style34\">Entran a formar parte del Consejo Escolar<span>\u00a0<\/span><span class=\"auto-style35\"><strong>4<\/strong><\/span><span>\u00a0<\/span>padres\/madres<\/span><\/td>\n<td class=\"auto-style32\">\u00a0<\/td>\n<td class=\"auto-style36\"><br class=\"auto-style34\" \/><span class=\"auto-style34\">Entra a formar parte del Consejo Escolar<span>\u00a0<\/span><span class=\"auto-style35\"><strong>1<\/strong><\/span><span>\u00a0<\/span>P.A.S.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>El Consejo escolar es un \u00f3rgano colegiado de Participaci\u00f3n de la comunidad educativa en el gobierno del centro. La Constituci\u00f3n Espa\u00f1ola, en su art\u00edculo 27, establece que \u00abLos profesores, los padres y, en su caso, los alumnos intervendr\u00e1n en el control y gesti\u00f3n de todos los centros sostenidos por la Administraci\u00f3n con fondos p\u00fablicos\u00bb; este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ELECCIONES AL CONSEJO ESCOLAR - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELECCIONES AL CONSEJO ESCOLAR - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"El Consejo escolar es un \u00f3rgano colegiado de Participaci\u00f3n de la comunidad educativa en el gobierno del centro. La Constituci\u00f3n Espa\u00f1ola, en su art\u00edculo 27, establece que &quot;Los profesores, los padres y, en su caso, los alumnos intervendr\u00e1n en el control y gesti\u00f3n de todos los centros sostenidos por la Administraci\u00f3n con fondos p\u00fablicos&quot;; este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-25T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:45:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/consejoescolar3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"headline\":\"ELECCIONES AL CONSEJO ESCOLAR\",\"datePublished\":\"2018-07-25T10:00:00+00:00\",\"dateModified\":\"2025-05-06T17:45:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/\"},\"wordCount\":365,\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/consejoescolar3.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/\",\"name\":\"ELECCIONES AL CONSEJO ESCOLAR - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/consejoescolar3.jpg\",\"datePublished\":\"2018-07-25T10:00:00+00:00\",\"dateModified\":\"2025-05-06T17:45:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/consejoescolar3.jpg\",\"contentUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/consejoescolar3.jpg\",\"width\":250,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2018\\\/07\\\/25\\\/elecciones-al-consejo-escolar-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ELECCIONES AL CONSEJO ESCOLAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/iesfernandoaguilar.es\"],\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/author\\\/nimda_faq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELECCIONES AL CONSEJO ESCOLAR - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/","og_locale":"es_ES","og_type":"article","og_title":"ELECCIONES AL CONSEJO ESCOLAR - IES Fernando Aguilar Quignon","og_description":"El Consejo escolar es un \u00f3rgano colegiado de Participaci\u00f3n de la comunidad educativa en el gobierno del centro. La Constituci\u00f3n Espa\u00f1ola, en su art\u00edculo 27, establece que \"Los profesores, los padres y, en su caso, los alumnos intervendr\u00e1n en el control y gesti\u00f3n de todos los centros sostenidos por la Administraci\u00f3n con fondos p\u00fablicos\"; este [&hellip;]","og_url":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/","og_site_name":"IES Fernando Aguilar Quignon","article_published_time":"2018-07-25T10:00:00+00:00","article_modified_time":"2025-05-06T17:45:11+00:00","og_image":[{"width":250,"height":132,"url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/consejoescolar3.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#article","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/"},"author":{"name":"admin","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"headline":"ELECCIONES AL CONSEJO ESCOLAR","datePublished":"2018-07-25T10:00:00+00:00","dateModified":"2025-05-06T17:45:11+00:00","mainEntityOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/"},"wordCount":365,"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/consejoescolar3.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/","url":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/","name":"ELECCIONES AL CONSEJO ESCOLAR - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#primaryimage"},"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/consejoescolar3.jpg","datePublished":"2018-07-25T10:00:00+00:00","dateModified":"2025-05-06T17:45:11+00:00","author":{"@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"breadcrumb":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#primaryimage","url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/consejoescolar3.jpg","contentUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/consejoescolar3.jpg","width":250,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2018\/07\/25\/elecciones-al-consejo-escolar-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iesfernandoaguilar.es\/"},{"@type":"ListItem","position":2,"name":"ELECCIONES AL CONSEJO ESCOLAR"}]},{"@type":"WebSite","@id":"https:\/\/iesfernandoaguilar.es\/#website","url":"https:\/\/iesfernandoaguilar.es\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iesfernandoaguilar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/iesfernandoaguilar.es"],"url":"https:\/\/iesfernandoaguilar.es\/index.php\/author\/nimda_faq\/"}]}},"_links":{"self":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/comments?post=4601"}],"version-history":[{"count":3,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4601\/revisions"}],"predecessor-version":[{"id":4604,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4601\/revisions\/4604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media\/4232"}],"wp:attachment":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media?parent=4601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/categories?post=4601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/tags?post=4601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}