{"id":4472,"date":"2017-05-20T21:31:00","date_gmt":"2017-05-20T21:31:00","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?p=4472"},"modified":"2025-05-06T17:45:12","modified_gmt":"2025-05-06T17:45:12","slug":"pruebas-de-acceso-a-ciclos-formativos-2","status":"publish","type":"post","link":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/","title":{"rendered":"PRUEBAS DE ACCESO A CICLOS FORMATIVOS"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Una vez cerrado el plazo de inscripci\u00f3n para la Prueba de Acceso a Ciclos Formativos de Grado Superior (Opci\u00f3n B) en nuestro IES, aqu\u00ed tienes el Calendario con las fechas a tener en cuenta:<\/p>\n<p>MARTES 6 de JUNIO: Listas PROVISIONALES de Admitidos y Excluidos. (Tablones del IES y Secretar\u00eda Virtual de la Junta)<br \/>7, 8 y 9 JUNIO: Periodo de Reclamaci\u00f3n a las Listas Provisionales. (Secretar\u00eda del IES)<br \/>LUNES 12 de JUNIO: Listas DEFINITIVAS de Admitidos y Excluidos. (Tablones del IES y Secretar\u00eda Virtual de la Junta)<br \/>MARTES 13 de JUNIO: D\u00eda del examen:<br \/>Parte Espec\u00edfica: de 9:30 a 13:00 h.<br \/>Parte Com\u00fan: de 16:00 a 20:00 h.<br \/>Desde aqu\u00ed puedes entrar en la <span style=\"color: #00ccff;\"><a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/solicitudes\/#PRUACC\" target=\"_blank\" rel=\"noopener\" style=\"color: #00ccff;\">[ SECRETAR\u00cdA VIRTUAL ]<\/a><\/span><\/p>\n<p>Aqu\u00ed puedes consultar toda la informaci\u00f3n sobre las pruebas: horarios, contenidos, ex\u00e1menes anteriores: <a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portals\/web\/formacion-profesional-andaluza\/quiero-formarme\/pruebas-y-procedimientos\/pruebas-acceso\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #00ccff;\">[ MAS INFORMACI\u00d3N ]<\/span><\/a><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Una vez cerrado el plazo de inscripci\u00f3n para la Prueba de Acceso a Ciclos Formativos de Grado Superior (Opci\u00f3n B) en nuestro IES, aqu\u00ed tienes el Calendario con las fechas a tener en cuenta: MARTES 6 de JUNIO: Listas PROVISIONALES de Admitidos y Excluidos. (Tablones del IES y Secretar\u00eda Virtual de la Junta)7, 8 y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRUEBAS DE ACCESO A CICLOS FORMATIVOS - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRUEBAS DE ACCESO A CICLOS FORMATIVOS - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"Una vez cerrado el plazo de inscripci\u00f3n para la Prueba de Acceso a Ciclos Formativos de Grado Superior (Opci\u00f3n B) en nuestro IES, aqu\u00ed tienes el Calendario con las fechas a tener en cuenta: MARTES 6 de JUNIO: Listas PROVISIONALES de Admitidos y Excluidos. (Tablones del IES y Secretar\u00eda Virtual de la Junta)7, 8 y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-20T21:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:45:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/pruebasacceso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"headline\":\"PRUEBAS DE ACCESO A CICLOS FORMATIVOS\",\"datePublished\":\"2017-05-20T21:31:00+00:00\",\"dateModified\":\"2025-05-06T17:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/\"},\"wordCount\":211,\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/pruebasacceso.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/\",\"name\":\"PRUEBAS DE ACCESO A CICLOS FORMATIVOS - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/pruebasacceso.jpg\",\"datePublished\":\"2017-05-20T21:31:00+00:00\",\"dateModified\":\"2025-05-06T17:45:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/pruebasacceso.jpg\",\"contentUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/pruebasacceso.jpg\",\"width\":1279,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/05\\\/20\\\/pruebas-de-acceso-a-ciclos-formativos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRUEBAS DE ACCESO A CICLOS FORMATIVOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/iesfernandoaguilar.es\"],\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/author\\\/nimda_faq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRUEBAS DE ACCESO A CICLOS FORMATIVOS - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/","og_locale":"es_ES","og_type":"article","og_title":"PRUEBAS DE ACCESO A CICLOS FORMATIVOS - IES Fernando Aguilar Quignon","og_description":"Una vez cerrado el plazo de inscripci\u00f3n para la Prueba de Acceso a Ciclos Formativos de Grado Superior (Opci\u00f3n B) en nuestro IES, aqu\u00ed tienes el Calendario con las fechas a tener en cuenta: MARTES 6 de JUNIO: Listas PROVISIONALES de Admitidos y Excluidos. (Tablones del IES y Secretar\u00eda Virtual de la Junta)7, 8 y [&hellip;]","og_url":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/","og_site_name":"IES Fernando Aguilar Quignon","article_published_time":"2017-05-20T21:31:00+00:00","article_modified_time":"2025-05-06T17:45:12+00:00","og_image":[{"width":1279,"height":670,"url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/pruebasacceso.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#article","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/"},"author":{"name":"admin","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"headline":"PRUEBAS DE ACCESO A CICLOS FORMATIVOS","datePublished":"2017-05-20T21:31:00+00:00","dateModified":"2025-05-06T17:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/"},"wordCount":211,"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/pruebasacceso.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/","url":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/","name":"PRUEBAS DE ACCESO A CICLOS FORMATIVOS - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#primaryimage"},"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/pruebasacceso.jpg","datePublished":"2017-05-20T21:31:00+00:00","dateModified":"2025-05-06T17:45:12+00:00","author":{"@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"breadcrumb":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#primaryimage","url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/pruebasacceso.jpg","contentUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/pruebasacceso.jpg","width":1279,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/05\/20\/pruebas-de-acceso-a-ciclos-formativos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iesfernandoaguilar.es\/"},{"@type":"ListItem","position":2,"name":"PRUEBAS DE ACCESO A CICLOS FORMATIVOS"}]},{"@type":"WebSite","@id":"https:\/\/iesfernandoaguilar.es\/#website","url":"https:\/\/iesfernandoaguilar.es\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iesfernandoaguilar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/iesfernandoaguilar.es"],"url":"https:\/\/iesfernandoaguilar.es\/index.php\/author\/nimda_faq\/"}]}},"_links":{"self":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/comments?post=4472"}],"version-history":[{"count":3,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4472\/revisions"}],"predecessor-version":[{"id":4475,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4472\/revisions\/4475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media\/4272"}],"wp:attachment":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media?parent=4472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/categories?post=4472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/tags?post=4472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}