{"id":4447,"date":"2017-04-01T21:22:00","date_gmt":"2017-04-01T21:22:00","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?p=4447"},"modified":"2025-05-06T17:45:12","modified_gmt":"2025-05-06T17:45:12","slug":"fotos-de-la-semana-de-las-profesiones","status":"publish","type":"post","link":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/","title":{"rendered":"FOTOS DE LA SEMANA DE LAS PROFESIONES"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Hemos celebrado del 3 al 7 de Abril la Semana de las Profesiones, Jornadas de Orientaci\u00f3n Vocacional y Profesional dirigida al alumnado de ESO, BACHILLERATO y FPB. Inclu\u00eda charlas con profesionales de distintos \u00e1mbitos y profesiones, as\u00ed como visitas guiadas a los Ciclos Formativos de Grado Medio de nuestro instituto.<\/p>[\/et_pb_text][et_pb_button button_text=\u00bbAlb\u00fam\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb button_alignment=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; button_url=\u00bbhttps:\/\/eu.zonerama.com\/IESFernandoAguilar\/Album\/2851687&#8243; url_new_window=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Hemos celebrado del 3 al 7 de Abril la Semana de las Profesiones, Jornadas de Orientaci\u00f3n Vocacional y Profesional dirigida al alumnado de ESO, BACHILLERATO y FPB. Inclu\u00eda charlas con profesionales de distintos \u00e1mbitos y profesiones, as\u00ed como visitas guiadas a los Ciclos Formativos de Grado Medio de nuestro instituto.<\/p>\n","protected":false},"author":1,"featured_media":4281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FOTOS DE LA SEMANA DE LAS PROFESIONES - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FOTOS DE LA SEMANA DE LAS PROFESIONES - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"Hemos celebrado del 3 al 7 de Abril la Semana de las Profesiones, Jornadas de Orientaci\u00f3n Vocacional y Profesional dirigida al alumnado de ESO, BACHILLERATO y FPB. Inclu\u00eda charlas con profesionales de distintos \u00e1mbitos y profesiones, as\u00ed como visitas guiadas a los Ciclos Formativos de Grado Medio de nuestro instituto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-01T21:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:45:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/semanaprofesiones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"headline\":\"FOTOS DE LA SEMANA DE LAS PROFESIONES\",\"datePublished\":\"2017-04-01T21:22:00+00:00\",\"dateModified\":\"2025-05-06T17:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/\"},\"wordCount\":167,\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semanaprofesiones.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/\",\"name\":\"FOTOS DE LA SEMANA DE LAS PROFESIONES - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semanaprofesiones.jpg\",\"datePublished\":\"2017-04-01T21:22:00+00:00\",\"dateModified\":\"2025-05-06T17:45:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semanaprofesiones.jpg\",\"contentUrl\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semanaprofesiones.jpg\",\"width\":230,\"height\":125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/2017\\\/04\\\/01\\\/fotos-de-la-semana-de-las-profesiones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FOTOS DE LA SEMANA DE LAS PROFESIONES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#\\\/schema\\\/person\\\/92716e3f220c099c512cef8863b77a88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/iesfernandoaguilar.es\"],\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/author\\\/nimda_faq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FOTOS DE LA SEMANA DE LAS PROFESIONES - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/","og_locale":"es_ES","og_type":"article","og_title":"FOTOS DE LA SEMANA DE LAS PROFESIONES - IES Fernando Aguilar Quignon","og_description":"Hemos celebrado del 3 al 7 de Abril la Semana de las Profesiones, Jornadas de Orientaci\u00f3n Vocacional y Profesional dirigida al alumnado de ESO, BACHILLERATO y FPB. Inclu\u00eda charlas con profesionales de distintos \u00e1mbitos y profesiones, as\u00ed como visitas guiadas a los Ciclos Formativos de Grado Medio de nuestro instituto.","og_url":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/","og_site_name":"IES Fernando Aguilar Quignon","article_published_time":"2017-04-01T21:22:00+00:00","article_modified_time":"2025-05-06T17:45:12+00:00","og_image":[{"width":230,"height":125,"url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/semanaprofesiones.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#article","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/"},"author":{"name":"admin","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"headline":"FOTOS DE LA SEMANA DE LAS PROFESIONES","datePublished":"2017-04-01T21:22:00+00:00","dateModified":"2025-05-06T17:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/"},"wordCount":167,"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/semanaprofesiones.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/","url":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/","name":"FOTOS DE LA SEMANA DE LAS PROFESIONES - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#primaryimage"},"image":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#primaryimage"},"thumbnailUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/semanaprofesiones.jpg","datePublished":"2017-04-01T21:22:00+00:00","dateModified":"2025-05-06T17:45:12+00:00","author":{"@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88"},"breadcrumb":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#primaryimage","url":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/semanaprofesiones.jpg","contentUrl":"https:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/04\/semanaprofesiones.jpg","width":230,"height":125},{"@type":"BreadcrumbList","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/2017\/04\/01\/fotos-de-la-semana-de-las-profesiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iesfernandoaguilar.es\/"},{"@type":"ListItem","position":2,"name":"FOTOS DE LA SEMANA DE LAS PROFESIONES"}]},{"@type":"WebSite","@id":"https:\/\/iesfernandoaguilar.es\/#website","url":"https:\/\/iesfernandoaguilar.es\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iesfernandoaguilar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/iesfernandoaguilar.es\/#\/schema\/person\/92716e3f220c099c512cef8863b77a88","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/iesfernandoaguilar.es"],"url":"https:\/\/iesfernandoaguilar.es\/index.php\/author\/nimda_faq\/"}]}},"_links":{"self":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/comments?post=4447"}],"version-history":[{"count":3,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4447\/revisions"}],"predecessor-version":[{"id":4450,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/posts\/4447\/revisions\/4450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media\/4281"}],"wp:attachment":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media?parent=4447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/categories?post=4447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/tags?post=4447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}