{"id":4053,"date":"2026-05-21T11:27:09","date_gmt":"2026-05-21T11:27:09","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?page_id=4053"},"modified":"2026-05-25T16:04:25","modified_gmt":"2026-05-25T16:04:25","slug":"escuela-espacio-de-paz-2","status":"publish","type":"page","link":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/","title":{"rendered":"Escuela espacio de paz"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#0a0000&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_type=\u00bbcircular\u00bb background_color_gradient_stops=\u00bbrgba(51,51,51,0.5) 0%|rgba(1,10,6,0.5) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/ceipsp.es\/wp-content\/uploads\/WhatsApp-Image-2025-02-11-at-14.24.37.jpeg\u00bb background_position=\u00bbtop_left\u00bb background_vertical_offset=\u00bb42%\u00bb background_blend=\u00bbdarken\u00bb custom_padding=\u00bb||||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbEscuela Espacio de Paz\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbFujiyama 2|300|||||||\u00bb title_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#6D004C\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>La Red Andaluza \u00abEscuela: Espacio de Paz\u00bb es una red de centros interesados en compartir iniciativas, recursos y experiencias para la mejora de la convivencia escolar y la difusi\u00f3n de la Cultura de Paz, contrayendo un compromiso de profundizaci\u00f3n en aspectos concretos de su Plan de Convivencia. La normativa que regula el funcionamiento de la Red pone el acento en la cultura de la evaluaci\u00f3n, en la necesidad de visibilizar las buenas pr\u00e1cticas desarrolladas en los centros y en la voluntad de trabajar en red compartiendo propuestas, estrategias y recursos con toda la comunidad educativa.<\/p>\n<p>Entre las se\u00f1as de identidad de los centros que integran la Red Andaluza \u00abEscuela: Espacio de Paz\u00bb destacan la promoci\u00f3n de los valores propios de una sociedad democr\u00e1tica, el respeto mutuo, la igualdad, el di\u00e1logo, la solidaridad y la resoluci\u00f3n pac\u00edfica de los conflictos, contando con la participaci\u00f3n de toda la comunidad educativa en la vida de los centros y la vinculaci\u00f3n e implicaci\u00f3n con su entorno.<\/p>\n<p>Nuestro centro participa en modalidad\u00a0 intercentro, que supone la participaci\u00f3n coordinada de varios centros de una misma zona educativa.<\/p>\n<p>Otro aspecto a destacar es el compromiso que adquieren nuestro centros de participar en los Encuentros Zonales de la Red y las acciones formativas a las que se les convoca para facilitar su actualizaci\u00f3n y compartir experiencias y recursos con otros centros.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bb\u00c1mbitos de actuaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbFujiyama 2|300|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Desde la Red Andaluza \u00abEscuela: Espacio de Paz\u00bb se proponen seis \u00e1mbitos de profundizaci\u00f3n para la mejora de la convivencia escolar:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbMejora desde la gesti\u00f3n y organizaci\u00f3n\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe02c;||divi||400&#8243; icon_color=\u00bb#F16CB9&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbPrevenci\u00f3n de situaciones de riesgo para la convivencia\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe0dd;||divi||400&#8243; icon_color=\u00bb#F16CB9&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbDesarrollo de la participaci\u00f3n de la Comunidad Educativa\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf4c4;||fa||900&#8243; icon_color=\u00bb#F16CB9&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bb Intervenci\u00f3n ante conductas contrarias a la convivencia\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf05e;||fa||900&#8243; icon_color=\u00bb#F16CB9&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbPromoci\u00f3n de la convivencia y desarrollo de valores\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf0c0;||fa||900&#8243; icon_color=\u00bb#F16CB9&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbReeducaci\u00f3n de actitudes y restauraci\u00f3n de la convivencia\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf4c2;||fa||900&#8243; icon_color=\u00bb#F16CB9&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bb\u00bfQu\u00e9 hacemos en el centro?\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbFujiyama 2|300|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCelebraci\u00f3n del D\u00eda de la Paz (30 enero), junto al CEIP Tierno Galv\u00e1n.\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; title_text=\u00bbCaptura de pantalla 2025-05-12 191617&#8243; image=\u00bbhttps:\/\/eu.zonerama.com\/PublicAlbumCover\/9569147?width=234&#038;height=179&#038;topStrip=True&#038;mode=0&#038;photoId=0&#038;plusNumber=False&#038;v=639004364566970000&#8243; url=\u00bbhttps:\/\/eu.zonerama.com\/IESFernandoAguilar\/Album\/9569147&#8243; url_new_window=\u00bbon\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbJornadas de J\u00f3venes Migrantes\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; image=\u00bbhttps:\/\/eu.zonerama.com\/PublicAlbumCover\/13296449?width=234&#038;height=179&#038;topStrip=True&#038;mode=0&#038;photoId=0&#038;plusNumber=False&#038;v=639148634233500000&#8243; url=\u00bbhttps:\/\/eu.zonerama.com\/IESFernandoAguilar\/Album\/13296449&#8243; url_new_window=\u00bbon\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbGrupo de Mediadores\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb title_text=\u00bbmediadores\u00bb image=\u00bbhttps:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2026\/05\/mediadores.jpg\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCampa\u00f1as de Educaci\u00f3n en Valores y Exposiciones tem\u00e1ticas\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|600|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#6D004C\u00bb animation_style=\u00bbslide\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb title_text=\u00bbEscuela Espacio de Paz\u00bb image=\u00bbhttps:\/\/iesfernandoaguilar.es\/wp-content\/uploads\/2025\/05\/Escuela-Espacio-de-Paz-scaled.jpg\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Red Andaluza \u00abEscuela: Espacio de Paz\u00bb es una red de centros interesados en compartir iniciativas, recursos y experiencias para la mejora de la convivencia escolar y la difusi\u00f3n de la Cultura de Paz, contrayendo un compromiso de profundizaci\u00f3n en aspectos concretos de su Plan de Convivencia. La normativa que regula el funcionamiento de la [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-4053","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escuela espacio de paz - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuela espacio de paz - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"La Red Andaluza \u00abEscuela: Espacio de Paz\u00bb es una red de centros interesados en compartir iniciativas, recursos y experiencias para la mejora de la convivencia escolar y la difusi\u00f3n de la Cultura de Paz, contrayendo un compromiso de profundizaci\u00f3n en aspectos concretos de su Plan de Convivencia. La normativa que regula el funcionamiento de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-25T16:04:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/escuela-espacio-de-paz-2\\\/\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/escuela-espacio-de-paz-2\\\/\",\"name\":\"Escuela espacio de paz - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\"},\"datePublished\":\"2026-05-21T11:27:09+00:00\",\"dateModified\":\"2026-05-25T16:04:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/escuela-espacio-de-paz-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/escuela-espacio-de-paz-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/index.php\\\/escuela-espacio-de-paz-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuela espacio de paz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/#website\",\"url\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iesfernandoaguilar.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuela espacio de paz - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/","og_locale":"es_ES","og_type":"article","og_title":"Escuela espacio de paz - IES Fernando Aguilar Quignon","og_description":"La Red Andaluza \u00abEscuela: Espacio de Paz\u00bb es una red de centros interesados en compartir iniciativas, recursos y experiencias para la mejora de la convivencia escolar y la difusi\u00f3n de la Cultura de Paz, contrayendo un compromiso de profundizaci\u00f3n en aspectos concretos de su Plan de Convivencia. La normativa que regula el funcionamiento de la [&hellip;]","og_url":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/","og_site_name":"IES Fernando Aguilar Quignon","article_modified_time":"2026-05-25T16:04:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/","url":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/","name":"Escuela espacio de paz - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/iesfernandoaguilar.es\/#website"},"datePublished":"2026-05-21T11:27:09+00:00","dateModified":"2026-05-25T16:04:25+00:00","breadcrumb":{"@id":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iesfernandoaguilar.es\/index.php\/escuela-espacio-de-paz-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iesfernandoaguilar.es\/"},{"@type":"ListItem","position":2,"name":"Escuela espacio de paz"}]},{"@type":"WebSite","@id":"https:\/\/iesfernandoaguilar.es\/#website","url":"https:\/\/iesfernandoaguilar.es\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iesfernandoaguilar.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/pages\/4053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/comments?post=4053"}],"version-history":[{"count":5,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/pages\/4053\/revisions"}],"predecessor-version":[{"id":6575,"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/pages\/4053\/revisions\/6575"}],"wp:attachment":[{"href":"https:\/\/iesfernandoaguilar.es\/index.php\/wp-json\/wp\/v2\/media?parent=4053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}